{"id":10859,"date":"2025-12-18T08:00:02","date_gmt":"2025-12-18T07:00:02","guid":{"rendered":"https:\/\/menorcapreservation.org\/?p=10859"},"modified":"2025-12-18T17:01:20","modified_gmt":"2025-12-18T16:01:20","slug":"1st-year-results-of-our-partnership-with-the-tui-care-foundation","status":"publish","type":"post","link":"https:\/\/menorcapreservation.org\/es\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/","title":{"rendered":"Resultados del 1er a\u00f1o de nuestra colaboraci\u00f3n con la TUI Care Foundation"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":5,"featured_media":10861,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"give_campaign_id":0,"footnotes":""},"categories":[12,1,11],"tags":[],"class_list":["post-10859","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-grants","category-in-the-news","category-press-releases"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1st Year results of our partnership with the TUI Care Foundation | Menorca Preservation<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/menorcapreservation.org\/es\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1st Year results of our partnership with the TUI Care Foundation | Menorca Preservation\" \/>\n<meta property=\"og:url\" content=\"https:\/\/menorcapreservation.org\/es\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/\" \/>\n<meta property=\"og:site_name\" content=\"Menorca Preservation\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-18T07:00:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T16:01:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/menorcapreservation.org\/wp-content\/uploads\/2025\/12\/MG_5659-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Sara DEustacchio\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Sara DEustacchio\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1st Year results of our partnership with the TUI Care Foundation | Menorca Preservation","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/menorcapreservation.org\/es\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/","og_locale":"es_ES","og_type":"article","og_title":"1st Year results of our partnership with the TUI Care Foundation | Menorca Preservation","og_url":"https:\/\/menorcapreservation.org\/es\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/","og_site_name":"Menorca Preservation","article_published_time":"2025-12-18T07:00:02+00:00","article_modified_time":"2025-12-18T16:01:20+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/menorcapreservation.org\/wp-content\/uploads\/2025\/12\/MG_5659-scaled.jpg","type":"image\/jpeg"}],"author":"Sara DEustacchio","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Sara DEustacchio","Tiempo de lectura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/#article","isPartOf":{"@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/"},"author":{"name":"Sara DEustacchio","@id":"https:\/\/menorcapreservation.org\/#\/schema\/person\/f0f039ddce8a78e1ad31bc7acb42b88a"},"headline":"1st Year results of our partnership with the TUI Care Foundation","datePublished":"2025-12-18T07:00:02+00:00","dateModified":"2025-12-18T16:01:20+00:00","mainEntityOfPage":{"@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/"},"wordCount":11,"publisher":{"@id":"https:\/\/menorcapreservation.org\/#organization"},"image":{"@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/#primaryimage"},"thumbnailUrl":"https:\/\/menorcapreservation.org\/wp-content\/uploads\/2025\/12\/MG_5659-scaled.jpg","articleSection":["Grants","In the news","Press releases"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/","url":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/","name":"1st Year results of our partnership with the TUI Care Foundation | Menorca Preservation","isPartOf":{"@id":"https:\/\/menorcapreservation.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/#primaryimage"},"image":{"@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/#primaryimage"},"thumbnailUrl":"https:\/\/menorcapreservation.org\/wp-content\/uploads\/2025\/12\/MG_5659-scaled.jpg","datePublished":"2025-12-18T07:00:02+00:00","dateModified":"2025-12-18T16:01:20+00:00","breadcrumb":{"@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/#primaryimage","url":"https:\/\/menorcapreservation.org\/wp-content\/uploads\/2025\/12\/MG_5659-scaled.jpg","contentUrl":"https:\/\/menorcapreservation.org\/wp-content\/uploads\/2025\/12\/MG_5659-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/menorcapreservation.org\/1st-year-results-of-our-partnership-with-the-tui-care-foundation\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/menorcapreservation.org\/"},{"@type":"ListItem","position":2,"name":"1st Year results of our partnership with the TUI Care Foundation"}]},{"@type":"WebSite","@id":"https:\/\/menorcapreservation.org\/#website","url":"https:\/\/menorcapreservation.org\/","name":"Menorca Preservation","description":"Colaborando juntos de manera hol\u00edstica hacia un futuro m\u00e1s sostenible.","publisher":{"@id":"https:\/\/menorcapreservation.org\/#organization"},"alternateName":"MeP","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/menorcapreservation.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/menorcapreservation.org\/#organization","name":"Menorca Preservation","alternateName":"MeP","url":"https:\/\/menorcapreservation.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/menorcapreservation.org\/#\/schema\/logo\/image\/","url":"https:\/\/menorcapreservation.org\/wp-content\/uploads\/2024\/07\/portada-home-1.png","contentUrl":"https:\/\/menorcapreservation.org\/wp-content\/uploads\/2024\/07\/portada-home-1.png","width":600,"height":300,"caption":"Menorca Preservation"},"image":{"@id":"https:\/\/menorcapreservation.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/menorcapreservation.org\/#\/schema\/person\/f0f039ddce8a78e1ad31bc7acb42b88a","name":"Sara DEustacchio","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/f580c00e2fe8002b1b18b6e48c76538c8942e9b3fb36c48af56f57e81f943c43?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/f580c00e2fe8002b1b18b6e48c76538c8942e9b3fb36c48af56f57e81f943c43?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/f580c00e2fe8002b1b18b6e48c76538c8942e9b3fb36c48af56f57e81f943c43?s=96&d=mm&r=g","caption":"Sara DEustacchio"},"url":"https:\/\/menorcapreservation.org\/es\/author\/sara-deustacchio\/"}]}},"_links":{"self":[{"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/posts\/10859","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/comments?post=10859"}],"version-history":[{"count":3,"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/posts\/10859\/revisions"}],"predecessor-version":[{"id":10863,"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/posts\/10859\/revisions\/10863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/media\/10861"}],"wp:attachment":[{"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/media?parent=10859"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/categories?post=10859"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/menorcapreservation.org\/es\/wp-json\/wp\/v2\/tags?post=10859"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}